{"id":10926,"date":"2023-06-05T16:46:39","date_gmt":"2023-06-05T21:46:39","guid":{"rendered":"https:\/\/www.dadiscartagena.gov.co\/?p=10926"},"modified":"2023-06-05T17:02:41","modified_gmt":"2023-06-05T22:02:41","slug":"semana-8-2","status":"publish","type":"post","link":"https:\/\/www.dadiscartagena.gov.co\/index.php\/2023\/06\/05\/semana-8-2\/","title":{"rendered":"SEMANA &#8211; 8"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10926\" class=\"elementor elementor-10926\">\n\t\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-44959fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44959fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57f545f\" data-id=\"57f545f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7a7150 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"b7a7150\" data-element_type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-b7a7150\" data-accordion-id=\"b7a7150\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n    <div class=\"eael-accordion-list\">\n                <div id=\"cncer-de-mama-y-cuello-uterino\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1921\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1921\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">C\u00c1NCER DE MAMA Y CUELLO UTERINO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1921\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"cncer-de-mama-y-cuello-uterino\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/cancer_mama_cuello_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"crnicas-no-transmisibles-y-lesiones-por-plvora\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1922\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-1922\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">CR\u00d3NICAS NO TRANSMISIBLES Y LESIONES POR P\u00d3LVORA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1922\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"crnicas-no-transmisibles-y-lesiones-por-plvora\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/cronicas_no_transmisibles_sem_8_2018.pdf\">VER INFORME &gt;<\/a>\u00a0<\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"intoxicaciones\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1923\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-1923\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INTOXICACIONES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1923\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"intoxicaciones\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/factores_riesgo_ambiental_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"infecciones-asociadas-a-la-atencin-en-salud\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1924\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-1924\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INFECCIONES ASOCIADAS A LA ATENCI\u00d3N EN SALUD<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1924\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"infecciones-asociadas-a-la-atencin-en-salud\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/iaas_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"inmunoprevenibles\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1925\" data-tab=\"5\" role=\"tab\" aria-controls=\"elementor-tab-content-1925\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INMUNOPREVENIBLES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1925\" class=\"eael-accordion-content clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"inmunoprevenibles\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/inmunoprevenibles_sem_8_2018.pdf\">VER INFORME &gt;\u00a0<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"intento-de-suicidio\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1926\" data-tab=\"6\" role=\"tab\" aria-controls=\"elementor-tab-content-1926\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INTENTO DE SUICIDIO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1926\" class=\"eael-accordion-content clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"intento-de-suicidio\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/intento_suicidio_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"ira-y-vigilancia-integral-de-muertes-en-menores-de-5-aos-por-ira-eda-y-asociada-a-desnutricin\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1927\" data-tab=\"7\" role=\"tab\" aria-controls=\"elementor-tab-content-1927\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">IRA Y VIGILANCIA INTEGRAL DE MUERTES EN MENORES DE 5 A\u00d1OS POR IRA, EDA Y ASOCIADA A DESNUTRICI\u00d3N<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1927\" class=\"eael-accordion-content clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"ira-y-vigilancia-integral-de-muertes-en-menores-de-5-aos-por-ira-eda-y-asociada-a-desnutricin\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/ira_sem_8_2018.pdf\">VER INFORME &gt;\u00a0<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"lesiones-por-causas-externas\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1928\" data-tab=\"8\" role=\"tab\" aria-controls=\"elementor-tab-content-1928\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">LESIONES POR CAUSAS EXTERNAS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1928\" class=\"eael-accordion-content clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"lesiones-por-causas-externas\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/lesiones_causas_externas_sem_8_2018.pdf\">VER INFORME &gt;\u00a0<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"maternidad-segura\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1929\" data-tab=\"9\" role=\"tab\" aria-controls=\"elementor-tab-content-1929\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">MATERNIDAD SEGURA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1929\" class=\"eael-accordion-content clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"maternidad-segura\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/maternidad_segura_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"tuberculosis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19210\" data-tab=\"10\" role=\"tab\" aria-controls=\"elementor-tab-content-19210\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">TUBERCULOSIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19210\" class=\"eael-accordion-content clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"tuberculosis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/tuberculosis__lepra_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"vih-sida\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19211\" data-tab=\"11\" role=\"tab\" aria-controls=\"elementor-tab-content-19211\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">VIH SIDA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19211\" class=\"eael-accordion-content clearfix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"vih-sida\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/vih_sida_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"-zoonosis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19212\" data-tab=\"12\" role=\"tab\" aria-controls=\"elementor-tab-content-19212\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\"> ZOONOSIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19212\" class=\"eael-accordion-content clearfix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"-zoonosis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/zoonosis_sem_8_2018.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>C\u00c1NCER DE MAMA Y CUELLO UTERINO VER INFORME CR\u00d3NICAS NO TRANSMISIBLES Y LESIONES POR P\u00d3LVORA VER INFORME &gt;\u00a0 INTOXICACIONES VER INFORME INFECCIONES ASOCIADAS A LA ATENCI\u00d3N EN SALUD VER INFORME&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[70],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/10926"}],"collection":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/comments?post=10926"}],"version-history":[{"count":19,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/10926\/revisions"}],"predecessor-version":[{"id":10958,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/10926\/revisions\/10958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media?parent=10926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/categories?post=10926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/tags?post=10926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}