{"id":11700,"date":"2023-06-26T13:50:28","date_gmt":"2023-06-26T18:50:28","guid":{"rendered":"https:\/\/www.dadiscartagena.gov.co\/?p=11700"},"modified":"2023-06-26T14:23:50","modified_gmt":"2023-06-26T19:23:50","slug":"semana-28","status":"publish","type":"post","link":"https:\/\/www.dadiscartagena.gov.co\/index.php\/2023\/06\/26\/semana-28\/","title":{"rendered":"SEMANA &#8211; 28"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11700\" class=\"elementor elementor-11700\">\n\t\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-44959fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44959fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57f545f\" data-id=\"57f545f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7a7150 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"b7a7150\" data-element_type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-b7a7150\" data-accordion-id=\"b7a7150\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n    <div class=\"eael-accordion-list\">\n                <div id=\"accidente-ofdico\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1921\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1921\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ACCIDENTE OF\u00cdDICO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1921\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"accidente-ofdico\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/accidente_ofidico_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"agresiones-por-animales-petencialmente-transmisores-de-rabia\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1922\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-1922\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">AGRESIONES POR ANIMALES PETENCIALMENTE TRANSMISORES DE RABIA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1922\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"agresiones-por-animales-petencialmente-transmisores-de-rabia\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/agresiones_paptr_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"cancer-infantil\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1923\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-1923\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">CANCER INFANTIL<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1923\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"cancer-infantil\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/cancer_infantil_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"defectos-congenitos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1924\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-1924\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">DEFECTOS CONGENITOS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1924\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"defectos-congenitos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/defectos_congenitos_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"enfermedad-diarreica-aguda\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1925\" data-tab=\"5\" role=\"tab\" aria-controls=\"elementor-tab-content-1925\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ENFERMEDAD DIARREICA AGUDA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1925\" class=\"eael-accordion-content clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"enfermedad-diarreica-aguda\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/eda_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"esavi\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1926\" data-tab=\"6\" role=\"tab\" aria-controls=\"elementor-tab-content-1926\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ESAVI<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1926\" class=\"eael-accordion-content clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"esavi\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/esavi_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"enfermedades-transmitidas-por-alimentos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1927\" data-tab=\"7\" role=\"tab\" aria-controls=\"elementor-tab-content-1927\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ENFERMEDADES TRANSMITIDAS POR ALIMENTOS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1927\" class=\"eael-accordion-content clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"enfermedades-transmitidas-por-alimentos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/eta_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"enfermedades-transmitidas-por-vectores\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1928\" data-tab=\"8\" role=\"tab\" aria-controls=\"elementor-tab-content-1928\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ENFERMEDADES TRANSMITIDAS POR VECTORES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1928\" class=\"eael-accordion-content clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"enfermedades-transmitidas-por-vectores\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/etv_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"hepatitis-a\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1929\" data-tab=\"9\" role=\"tab\" aria-controls=\"elementor-tab-content-1929\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">HEPATITIS A<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1929\" class=\"eael-accordion-content clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"hepatitis-a\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/hepatitis_a_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"intoxicaciones\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19210\" data-tab=\"10\" role=\"tab\" aria-controls=\"elementor-tab-content-19210\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INTOXICACIONES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19210\" class=\"eael-accordion-content clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"intoxicaciones\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/intoxicaciones_sem_28_2015.pdf\" data-wplink-edit=\"true\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"ira-y-vigilancia-integral-de-muertes-en-menores-de-5-aos-por-ira-eda-y-asociada-a-desnutricin\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19211\" data-tab=\"11\" role=\"tab\" aria-controls=\"elementor-tab-content-19211\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">IRA Y VIGILANCIA INTEGRAL DE MUERTES EN MENORES DE 5 A\u00d1OS POR IRA, EDA Y ASOCIADA A DESNUTRICI\u00d3N<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19211\" class=\"eael-accordion-content clearfix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"ira-y-vigilancia-integral-de-muertes-en-menores-de-5-aos-por-ira-eda-y-asociada-a-desnutricin\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/ira_sem_28_2015.pdf\">VER INFORME &gt;\u00a0<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"leptospirosis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19212\" data-tab=\"12\" role=\"tab\" aria-controls=\"elementor-tab-content-19212\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">LEPTOSPIROSIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19212\" class=\"eael-accordion-content clearfix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"leptospirosis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/leptospirosis_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"lesiones-por-polvora\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19213\" data-tab=\"13\" role=\"tab\" aria-controls=\"elementor-tab-content-19213\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">LESIONES POR POLVORA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19213\" class=\"eael-accordion-content clearfix\" data-tab=\"13\" role=\"tabpanel\" aria-labelledby=\"lesiones-por-polvora\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/lesiones_polvora_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"maternidad-segura\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19214\" data-tab=\"14\" role=\"tab\" aria-controls=\"elementor-tab-content-19214\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">MATERNIDAD SEGURA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19214\" class=\"eael-accordion-content clearfix\" data-tab=\"14\" role=\"tabpanel\" aria-labelledby=\"maternidad-segura\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/maternidad_segura_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"meningitis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19215\" data-tab=\"15\" role=\"tab\" aria-controls=\"elementor-tab-content-19215\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">MENINGITIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19215\" class=\"eael-accordion-content clearfix\" data-tab=\"15\" role=\"tabpanel\" aria-labelledby=\"meningitis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/meningitis_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"parotiditis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19216\" data-tab=\"16\" role=\"tab\" aria-controls=\"elementor-tab-content-19216\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">PAROTIDITIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19216\" class=\"eael-accordion-content clearfix\" data-tab=\"16\" role=\"tabpanel\" aria-labelledby=\"parotiditis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/parotiditis_sem_24_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"sarampion-rubeola-pfa-ttano-accidental\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19217\" data-tab=\"17\" role=\"tab\" aria-controls=\"elementor-tab-content-19217\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">SARAMPION, RUBEOLA, PFA, T\u00c9TANO ACCIDENTAL<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19217\" class=\"eael-accordion-content clearfix\" data-tab=\"17\" role=\"tabpanel\" aria-labelledby=\"sarampion-rubeola-pfa-ttano-accidental\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/sarampion_rubeola_pfa_tetano_accidental_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"sfilis-congnita-hepatitis-b\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19218\" data-tab=\"18\" role=\"tab\" aria-controls=\"elementor-tab-content-19218\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">S\u00cdFILIS CONG\u00c9NITA, HEPATITIS B<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19218\" class=\"eael-accordion-content clearfix\" data-tab=\"18\" role=\"tabpanel\" aria-labelledby=\"sfilis-congnita-hepatitis-b\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/sifilis_congenita_hepatitis_b_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"intento-de-suicidio\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19219\" data-tab=\"19\" role=\"tab\" aria-controls=\"elementor-tab-content-19219\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INTENTO DE SUICIDIO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19219\" class=\"eael-accordion-content clearfix\" data-tab=\"19\" role=\"tabpanel\" aria-labelledby=\"intento-de-suicidio\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/suicidios_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"tuberculosis-lepra\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19220\" data-tab=\"20\" role=\"tab\" aria-controls=\"elementor-tab-content-19220\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">TUBERCULOSIS - LEPRA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19220\" class=\"eael-accordion-content clearfix\" data-tab=\"20\" role=\"tabpanel\" aria-labelledby=\"tuberculosis-lepra\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/tuberculosis_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"tosferina\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19221\" data-tab=\"21\" role=\"tab\" aria-controls=\"elementor-tab-content-19221\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">TOSFERINA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19221\" class=\"eael-accordion-content clearfix\" data-tab=\"21\" role=\"tabpanel\" aria-labelledby=\"tosferina\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/tosferina_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"vih-sida\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19222\" data-tab=\"22\" role=\"tab\" aria-controls=\"elementor-tab-content-19222\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">VIH - SIDA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19222\" class=\"eael-accordion-content clearfix\" data-tab=\"22\" role=\"tabpanel\" aria-labelledby=\"vih-sida\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/vih_sem_28_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"violenca-de-gnero\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19223\" data-tab=\"23\" role=\"tab\" aria-controls=\"elementor-tab-content-19223\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">VIOLENCA DE G\u00c9NERO.<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19223\" class=\"eael-accordion-content clearfix\" data-tab=\"23\" role=\"tabpanel\" aria-labelledby=\"violenca-de-gnero\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/violencia_genero_sem_24_2015.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ACCIDENTE OF\u00cdDICO VER INFORME AGRESIONES POR ANIMALES PETENCIALMENTE TRANSMISORES DE RABIA VER INFORME CANCER INFANTIL VER INFORME DEFECTOS CONGENITOS VER INFORME ENFERMEDAD DIARREICA AGUDA VER INFORME ESAVI VER INFORME ENFERMEDADES&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[68],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/11700"}],"collection":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/comments?post=11700"}],"version-history":[{"count":73,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/11700\/revisions"}],"predecessor-version":[{"id":11798,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/11700\/revisions\/11798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media?parent=11700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/categories?post=11700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/tags?post=11700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}