{"id":12476,"date":"2023-06-30T10:54:07","date_gmt":"2023-06-30T15:54:07","guid":{"rendered":"https:\/\/www.dadiscartagena.gov.co\/?p=12476"},"modified":"2023-06-30T10:58:03","modified_gmt":"2023-06-30T15:58:03","slug":"semana-18","status":"publish","type":"post","link":"https:\/\/www.dadiscartagena.gov.co\/index.php\/2023\/06\/30\/semana-18\/","title":{"rendered":"SEMANA &#8211; 18"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12476\" class=\"elementor elementor-12476\">\n\t\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-44959fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44959fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57f545f\" data-id=\"57f545f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7a7150 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"b7a7150\" data-element_type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-b7a7150\" data-accordion-id=\"b7a7150\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n    <div class=\"eael-accordion-list\">\n                <div id=\"accidente-ofdico\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1921\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1921\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ACCIDENTE OF\u00cdDICO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1921\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"accidente-ofdico\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/accidente_ofidico_sem_18_2017.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"agresiones-por-animales-petencialmente-transmisores-de-rabia\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1922\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-1922\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">AGRESIONES POR ANIMALES PETENCIALMENTE TRANSMISORES DE RABIA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1922\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"agresiones-por-animales-petencialmente-transmisores-de-rabia\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/cancer_mama_cuello_sem_18_2017.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"cncer-de-mama-y-cuello-uterino\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1923\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-1923\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">C\u00c1NCER DE MAMA Y CUELLO UTERINO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1923\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"cncer-de-mama-y-cuello-uterino\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/cancer_mama_cuello_sem_17_2017.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"crnicas-no-transmisibles-y-lesiones-por-plvora\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1924\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-1924\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">CR\u00d3NICAS NO TRANSMISIBLES Y LESIONES POR P\u00d3LVORA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1924\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"crnicas-no-transmisibles-y-lesiones-por-plvora\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/06\/cronicas_no_transmisibles_sem_18_2017.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ACCIDENTE OF\u00cdDICO VER INFORME AGRESIONES POR ANIMALES PETENCIALMENTE TRANSMISORES DE RABIA VER INFORME C\u00c1NCER DE MAMA Y CUELLO UTERINO VER INFORME CR\u00d3NICAS NO TRANSMISIBLES Y LESIONES POR P\u00d3LVORA VER INFORME<\/p>\n","protected":false},"author":1,"featured_media":2783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/12476"}],"collection":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/comments?post=12476"}],"version-history":[{"count":10,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/12476\/revisions"}],"predecessor-version":[{"id":12490,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/12476\/revisions\/12490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media?parent=12476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/categories?post=12476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/tags?post=12476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}