{"id":17029,"date":"2023-08-13T19:01:52","date_gmt":"2023-08-14T00:01:52","guid":{"rendered":"https:\/\/www.dadiscartagena.gov.co\/?p=17029"},"modified":"2023-08-13T19:11:57","modified_gmt":"2023-08-14T00:11:57","slug":"semana-48-3","status":"publish","type":"post","link":"https:\/\/www.dadiscartagena.gov.co\/index.php\/2023\/08\/13\/semana-48-3\/","title":{"rendered":"SEMANA &#8211; 48"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17029\" class=\"elementor elementor-17029\">\n\t\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-44959fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44959fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57f545f\" data-id=\"57f545f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7a7150 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"b7a7150\" data-element_type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-b7a7150\" data-accordion-id=\"b7a7150\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n    <div class=\"eael-accordion-list\">\n                <div id=\"carcel-de-ternera-y-san-diego\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1921\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1921\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">CARCEL DE TERNERA Y SAN DIEGO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1921\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"carcel-de-ternera-y-san-diego\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/carcel_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"crnicas-no-transmisibles-y-lesiones-por-plvora\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1922\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-1922\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">CR\u00d3NICAS NO TRANSMISIBLES Y LESIONES POR P\u00d3LVORA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1922\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"crnicas-no-transmisibles-y-lesiones-por-plvora\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/cronicas_no_transmisibles_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"enfermedad-diarreica-aguda\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1923\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-1923\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ENFERMEDAD DIARREICA AGUDA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1923\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"enfermedad-diarreica-aguda\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/eda_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"enfermedades-hurfanas\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1924\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-1924\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ENFERMEDADES HU\u00c9RFANAS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1924\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"enfermedades-hurfanas\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/enfermades_huerfanas_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"enfermedades-transmitidas-por-alimentos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1925\" data-tab=\"5\" role=\"tab\" aria-controls=\"elementor-tab-content-1925\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ENFERMEDADES TRANSMITIDAS POR ALIMENTOS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1925\" class=\"eael-accordion-content clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"enfermedades-transmitidas-por-alimentos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/eta_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"enfermedades-transmitidas-por-vectores\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1926\" data-tab=\"6\" role=\"tab\" aria-controls=\"elementor-tab-content-1926\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">ENFERMEDADES TRANSMITIDAS POR VECTORES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1926\" class=\"eael-accordion-content clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"enfermedades-transmitidas-por-vectores\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/etv_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"intoxicaciones\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1927\" data-tab=\"7\" role=\"tab\" aria-controls=\"elementor-tab-content-1927\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INTOXICACIONES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1927\" class=\"eael-accordion-content clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"intoxicaciones\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/factores_riesgo_ambiental_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"infecciones-asociadas-a-la-atencin-en-salud\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1928\" data-tab=\"8\" role=\"tab\" aria-controls=\"elementor-tab-content-1928\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INFECCIONES ASOCIADAS A LA ATENCI\u00d3N EN SALUD<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1928\" class=\"eael-accordion-content clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"infecciones-asociadas-a-la-atencin-en-salud\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/iaas_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"intento-de-suicidio\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1929\" data-tab=\"9\" role=\"tab\" aria-controls=\"elementor-tab-content-1929\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INTENTO DE SUICIDIO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1929\" class=\"eael-accordion-content clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"intento-de-suicidio\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/intento_suicidio_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"inmunoprevenibles\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19210\" data-tab=\"10\" role=\"tab\" aria-controls=\"elementor-tab-content-19210\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INMUNOPREVENIBLES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19210\" class=\"eael-accordion-content clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"inmunoprevenibles\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/inmunoprevenibles_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"ira-y-vigilancia-integral-de-muertes-en-menores-de-5-aos-por-ira-eda-y-asociada-a-desnutricin\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19211\" data-tab=\"11\" role=\"tab\" aria-controls=\"elementor-tab-content-19211\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">IRA Y VIGILANCIA INTEGRAL DE MUERTES EN MENORES DE 5 A\u00d1OS POR IRA, EDA Y ASOCIADA A DESNUTRICI\u00d3N<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19211\" class=\"eael-accordion-content clearfix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"ira-y-vigilancia-integral-de-muertes-en-menores-de-5-aos-por-ira-eda-y-asociada-a-desnutricin\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/ira_sem_47_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"infecciones-de-transmisin-sexual\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19212\" data-tab=\"12\" role=\"tab\" aria-controls=\"elementor-tab-content-19212\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">INFECCIONES DE TRANSMISI\u00d3N SEXUAL<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19212\" class=\"eael-accordion-content clearfix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"infecciones-de-transmisin-sexual\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/its_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"lesiones-por-causas-externas\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19213\" data-tab=\"13\" role=\"tab\" aria-controls=\"elementor-tab-content-19213\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">LESIONES POR CAUSAS EXTERNAS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19213\" class=\"eael-accordion-content clearfix\" data-tab=\"13\" role=\"tabpanel\" aria-labelledby=\"lesiones-por-causas-externas\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/lesiones_causas_externas_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"lesiones-por-polvora\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19214\" data-tab=\"14\" role=\"tab\" aria-controls=\"elementor-tab-content-19214\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">LESIONES POR POLVORA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19214\" class=\"eael-accordion-content clearfix\" data-tab=\"14\" role=\"tabpanel\" aria-labelledby=\"lesiones-por-polvora\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/lesiones_polvora_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"maternidad-segura\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19215\" data-tab=\"15\" role=\"tab\" aria-controls=\"elementor-tab-content-19215\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">MATERNIDAD SEGURA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19215\" class=\"eael-accordion-content clearfix\" data-tab=\"15\" role=\"tabpanel\" aria-labelledby=\"maternidad-segura\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/maternidad_segura_sem_48_2019.pdf\">VER INFORME &gt;<\/a>\u00a0<\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"tuberculosis-lepra\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19216\" data-tab=\"16\" role=\"tab\" aria-controls=\"elementor-tab-content-19216\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">TUBERCULOSIS - LEPRA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19216\" class=\"eael-accordion-content clearfix\" data-tab=\"16\" role=\"tabpanel\" aria-labelledby=\"tuberculosis-lepra\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/tuberculosis__lepra_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"vih-sida\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19217\" data-tab=\"17\" role=\"tab\" aria-controls=\"elementor-tab-content-19217\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">VIH - SIDA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19217\" class=\"eael-accordion-content clearfix\" data-tab=\"17\" role=\"tabpanel\" aria-labelledby=\"vih-sida\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/vih_sida_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"-zoonosis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19218\" data-tab=\"18\" role=\"tab\" aria-controls=\"elementor-tab-content-19218\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\"> ZOONOSIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19218\" class=\"eael-accordion-content clearfix\" data-tab=\"18\" role=\"tabpanel\" aria-labelledby=\"-zoonosis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2023\/08\/zoonosis_sem_48_2019.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CARCEL DE TERNERA Y SAN DIEGO VER INFORME CR\u00d3NICAS NO TRANSMISIBLES Y LESIONES POR P\u00d3LVORA VER INFORME ENFERMEDAD DIARREICA AGUDA VER INFORME ENFERMEDADES HU\u00c9RFANAS VER INFORME ENFERMEDADES TRANSMITIDAS POR ALIMENTOS&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[74],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/17029"}],"collection":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/comments?post=17029"}],"version-history":[{"count":10,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/17029\/revisions"}],"predecessor-version":[{"id":17039,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/17029\/revisions\/17039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media?parent=17029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/categories?post=17029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/tags?post=17029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}