{"id":28579,"date":"2026-03-18T22:11:02","date_gmt":"2026-03-19T03:11:02","guid":{"rendered":"https:\/\/www.dadiscartagena.gov.co\/?p=28579"},"modified":"2026-03-19T10:53:28","modified_gmt":"2026-03-19T15:53:28","slug":"semana-43-5","status":"publish","type":"post","link":"https:\/\/www.dadiscartagena.gov.co\/index.php\/2026\/03\/18\/semana-43-5\/","title":{"rendered":"SEMANA &#8211; 43"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"28579\" class=\"elementor elementor-28579\">\n\t\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-44959fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44959fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57f545f\" data-id=\"57f545f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7a7150 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"b7a7150\" data-element_type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-b7a7150\" data-accordion-id=\"b7a7150\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n    <div class=\"eael-accordion-list\">\n                <div id=\"boletin-accidente-ofidico\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1921\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1921\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN ACCIDENTE OFIDICO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1921\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"boletin-accidente-ofidico\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_ACCIDENTE_OFIDICO.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-agresiones-por-animales-potencialmente-transmisores-de-rabia-aptr\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1922\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-1922\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN AGRESIONES POR ANIMALES POTENCIALMENTE TRANSMISORES DE RABIA (APTR)<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1922\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"boletin-agresiones-por-animales-potencialmente-transmisores-de-rabia-aptr\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_AGRESIONES_POR_ANIMALES_POTENCIALMENTE_TRANSMISORES_DE_RABIA_APTR.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-cancer-de-mama-y-cuello-uterino\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1923\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-1923\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN CANCER DE MAMA Y CUELLO UTERINO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1923\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"boletin-cancer-de-mama-y-cuello-uterino\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_CANCER_DE_MAMA_Y_CUELLO_UTERINO.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-cancer-menores-de-18-aos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1924\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-1924\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN CANCER MENORES DE 18 A\u00d1OS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1924\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"boletin-cancer-menores-de-18-aos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_CANCER_MENORES_DE_18_ANOS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-covid-19\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1925\" data-tab=\"5\" role=\"tab\" aria-controls=\"elementor-tab-content-1925\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN COVID 19<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1925\" class=\"eael-accordion-content clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"boletin-covid-19\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_COVID-19.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-defectos-congenitos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1926\" data-tab=\"6\" role=\"tab\" aria-controls=\"elementor-tab-content-1926\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN DEFECTOS CONGENITOS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1926\" class=\"eael-accordion-content clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"boletin-defectos-congenitos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_DEFECTOS_CONGENITOS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-desnutricion-aguda-en-menores-5-aos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1927\" data-tab=\"7\" role=\"tab\" aria-controls=\"elementor-tab-content-1927\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN DESNUTRICION AGUDA EN MENORES 5 A\u00d1OS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1927\" class=\"eael-accordion-content clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"boletin-desnutricion-aguda-en-menores-5-aos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_DESNUTRICION_AGUDA_EN_MENORES_5_ANOS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-enfermedad-diarreica-aguda\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1928\" data-tab=\"8\" role=\"tab\" aria-controls=\"elementor-tab-content-1928\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN ENFERMEDAD DIARREICA AGUDA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1928\" class=\"eael-accordion-content clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"boletin-enfermedad-diarreica-aguda\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_ENFERMEDAD_DIARREICA_AGUDA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-enfermedades-huerfanas\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"1929\" data-tab=\"9\" role=\"tab\" aria-controls=\"elementor-tab-content-1929\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN ENFERMEDADES HUERFANAS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1929\" class=\"eael-accordion-content clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"boletin-enfermedades-huerfanas\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_ENFERMEDADES_HUERFANAS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-enfermedades-transmitidas-por-alimentos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19210\" data-tab=\"10\" role=\"tab\" aria-controls=\"elementor-tab-content-19210\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN ENFERMEDADES TRANSMITIDAS POR ALIMENTOS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19210\" class=\"eael-accordion-content clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"boletin-enfermedades-transmitidas-por-alimentos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_ENFERMEDADES_TRANSMITIDAS_POR_ALIMENTOS_COLECTIVA.pdf\">VER INFORME COLECTIVA<\/a><\/p><p>\u00a0<\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-epidemiologico-enfermedades-transmitidas-por-vectores\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19211\" data-tab=\"11\" role=\"tab\" aria-controls=\"elementor-tab-content-19211\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN EPIDEMIOLOGICO ENFERMEDADES TRANSMITIDAS POR VECTORES<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19211\" class=\"eael-accordion-content clearfix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"boletin-epidemiologico-enfermedades-transmitidas-por-vectores\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_EVENTO_SIN_ESTABLECER.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-evento-sin-establecer\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19212\" data-tab=\"12\" role=\"tab\" aria-controls=\"elementor-tab-content-19212\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN EVENTO SIN ESTABLECER<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19212\" class=\"eael-accordion-content clearfix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"boletin-evento-sin-establecer\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_EVENTO_SIN_ESTABLECER.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-fiebre-tifoidea-y-paratifoidea\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19213\" data-tab=\"13\" role=\"tab\" aria-controls=\"elementor-tab-content-19213\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN FIEBRE TIFOIDEA Y PARATIFOIDEA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19213\" class=\"eael-accordion-content clearfix\" data-tab=\"13\" role=\"tabpanel\" aria-labelledby=\"boletin-fiebre-tifoidea-y-paratifoidea\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_FIEBRE_TIFOIDEA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-hepatitis-a\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19214\" data-tab=\"14\" role=\"tab\" aria-controls=\"elementor-tab-content-19214\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN HEPATITIS A<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19214\" class=\"eael-accordion-content clearfix\" data-tab=\"14\" role=\"tabpanel\" aria-labelledby=\"boletin-hepatitis-a\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_HEPATITIS_A.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-infeccin-respiratoria-aguda-grave-irag-inusitada\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19215\" data-tab=\"15\" role=\"tab\" aria-controls=\"elementor-tab-content-19215\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN INFECCI\u00d3N RESPIRATORIA AGUDA GRAVE IRAG INUSITADA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19215\" class=\"eael-accordion-content clearfix\" data-tab=\"15\" role=\"tabpanel\" aria-labelledby=\"boletin-infeccin-respiratoria-aguda-grave-irag-inusitada\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_INFECCION_RESPIRATORIA_AGUDA_GRAVE_IRAG_INUSITADA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-intento-de-suicidio\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19216\" data-tab=\"16\" role=\"tab\" aria-controls=\"elementor-tab-content-19216\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN INTENTO DE SUICIDIO<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19216\" class=\"eael-accordion-content clearfix\" data-tab=\"16\" role=\"tabpanel\" aria-labelledby=\"boletin-intento-de-suicidio\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_INTENTO_DE_SUICIDIO.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-intoxicaciones-quimicas\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19217\" data-tab=\"17\" role=\"tab\" aria-controls=\"elementor-tab-content-19217\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN INTOXICACIONES QUIMICAS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19217\" class=\"eael-accordion-content clearfix\" data-tab=\"17\" role=\"tabpanel\" aria-labelledby=\"boletin-intoxicaciones-quimicas\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_INTOXICACIONES_POR_SUSTANCIAS_QUIMICAS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-leptospirosis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19218\" data-tab=\"18\" role=\"tab\" aria-controls=\"elementor-tab-content-19218\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN LEPTOSPIROSIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19218\" class=\"eael-accordion-content clearfix\" data-tab=\"18\" role=\"tabpanel\" aria-labelledby=\"boletin-leptospirosis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_LEPTOSPIROSIS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-meningitis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19219\" data-tab=\"19\" role=\"tab\" aria-controls=\"elementor-tab-content-19219\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN MENINGITIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19219\" class=\"eael-accordion-content clearfix\" data-tab=\"19\" role=\"tabpanel\" aria-labelledby=\"boletin-meningitis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_MENINGITIS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-micobacterias\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19220\" data-tab=\"20\" role=\"tab\" aria-controls=\"elementor-tab-content-19220\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN MICOBACTERIAS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19220\" class=\"eael-accordion-content clearfix\" data-tab=\"20\" role=\"tabpanel\" aria-labelledby=\"boletin-micobacterias\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_MICOBACTERIAS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-morbilidad-infeccin-respiratoria-aguda-morbilidad-por-ira\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19221\" data-tab=\"21\" role=\"tab\" aria-controls=\"elementor-tab-content-19221\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN MORBILIDAD INFECCI\u00d3N RESPIRATORIA AGUDA MORBILIDAD POR IRA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19221\" class=\"eael-accordion-content clearfix\" data-tab=\"21\" role=\"tabpanel\" aria-labelledby=\"boletin-morbilidad-infeccin-respiratoria-aguda-morbilidad-por-ira\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_MORBILIDAD_INFECCION_RESPIRATORIA_AGUDA_MORBILIDAD_POR_IRA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-morbilidad-materna-extrema-mme\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19222\" data-tab=\"22\" role=\"tab\" aria-controls=\"elementor-tab-content-19222\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN MORBILIDAD MATERNA EXTREMA (MME)<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19222\" class=\"eael-accordion-content clearfix\" data-tab=\"22\" role=\"tabpanel\" aria-labelledby=\"boletin-morbilidad-materna-extrema-mme\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_MORBILIDAD_MATERNA_EXTREMA_MME.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-mortalidad-perinatal-y-neonatal-tardia\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19223\" data-tab=\"23\" role=\"tab\" aria-controls=\"elementor-tab-content-19223\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN MORTALIDAD PERINATAL Y NEONATAL TARDIA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19223\" class=\"eael-accordion-content clearfix\" data-tab=\"23\" role=\"tabpanel\" aria-labelledby=\"boletin-mortalidad-perinatal-y-neonatal-tardia\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_MORTALIDAD_PERINATAL_Y_NEONATAL_TARDIA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-parotiditis\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19224\" data-tab=\"24\" role=\"tab\" aria-controls=\"elementor-tab-content-19224\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN PAROTIDITIS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19224\" class=\"eael-accordion-content clearfix\" data-tab=\"24\" role=\"tabpanel\" aria-labelledby=\"boletin-parotiditis\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_PAROTIDITIS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-sarampion\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19225\" data-tab=\"25\" role=\"tab\" aria-controls=\"elementor-tab-content-19225\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN SARAMPION<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19225\" class=\"eael-accordion-content clearfix\" data-tab=\"25\" role=\"tabpanel\" aria-labelledby=\"boletin-sarampion\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_SARAMPION.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-sfilis-congnita\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19226\" data-tab=\"26\" role=\"tab\" aria-controls=\"elementor-tab-content-19226\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN S\u00cdFILIS CONG\u00c9NITA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19226\" class=\"eael-accordion-content clearfix\" data-tab=\"26\" role=\"tabpanel\" aria-labelledby=\"boletin-sfilis-congnita\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_SIFILIS_CONGENITA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-sfilis-gestacional\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19227\" data-tab=\"27\" role=\"tab\" aria-controls=\"elementor-tab-content-19227\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN S\u00cdFILIS GESTACIONAL<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19227\" class=\"eael-accordion-content clearfix\" data-tab=\"27\" role=\"tabpanel\" aria-labelledby=\"boletin-sfilis-gestacional\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_SIFILIS_GESTACIONAL.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-tosferina\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19228\" data-tab=\"28\" role=\"tab\" aria-controls=\"elementor-tab-content-19228\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN TOSFERINA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19228\" class=\"eael-accordion-content clearfix\" data-tab=\"28\" role=\"tabpanel\" aria-labelledby=\"boletin-tosferina\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_TOSFERINA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-varicela\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19229\" data-tab=\"29\" role=\"tab\" aria-controls=\"elementor-tab-content-19229\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN VARICELA<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19229\" class=\"eael-accordion-content clearfix\" data-tab=\"29\" role=\"tabpanel\" aria-labelledby=\"boletin-varicela\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_VARICELA.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-vigilancia-integrada-de-muertes-por-ira-eda-dnt-en-menor-de-5-aos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19230\" data-tab=\"30\" role=\"tab\" aria-controls=\"elementor-tab-content-19230\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN VIGILANCIA INTEGRADA DE MUERTES POR IRA, EDA , DNT EN MENOR DE 5 A\u00d1OS<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19230\" class=\"eael-accordion-content clearfix\" data-tab=\"30\" role=\"tabpanel\" aria-labelledby=\"boletin-vigilancia-integrada-de-muertes-por-ira-eda-dnt-en-menor-de-5-aos\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_VIGILANCIA_INTEGRADA_DE_MUERTES_POR_IRA_EDA__DNT_EN_MENOR_DE_5_ANOS.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-vih\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19231\" data-tab=\"31\" role=\"tab\" aria-controls=\"elementor-tab-content-19231\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN VIH<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19231\" class=\"eael-accordion-content clearfix\" data-tab=\"31\" role=\"tabpanel\" aria-labelledby=\"boletin-vih\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_VIH.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><div class=\"eael-accordion-list\">\n                <div id=\"boletin-violencia-de-genero-e-intrafamiliar\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"19232\" data-tab=\"32\" role=\"tab\" aria-controls=\"elementor-tab-content-19232\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BOLETIN VIOLENCIA DE GE\u0301NERO E INTRAFAMILIAR<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-19232\" class=\"eael-accordion-content clearfix\" data-tab=\"32\" role=\"tabpanel\" aria-labelledby=\"boletin-violencia-de-genero-e-intrafamiliar\"><p><p><a href=\"https:\/\/www.dadiscartagena.gov.co\/wp-content\/uploads\/2026\/03\/B2025_43_BOLETIN_VIOLENCIA_DE_GENERO_E_INTRAFAMILIAR.pdf\">VER INFORME<\/a><\/p><\/p><\/div>\n                <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>BOLETIN ACCIDENTE OFIDICO VER INFORME BOLETIN AGRESIONES POR ANIMALES POTENCIALMENTE TRANSMISORES DE RABIA (APTR) VER INFORME BOLETIN CANCER DE MAMA Y CUELLO UTERINO VER INFORME BOLETIN CANCER MENORES DE 18&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[78],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/28579"}],"collection":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/comments?post=28579"}],"version-history":[{"count":7,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/28579\/revisions"}],"predecessor-version":[{"id":28663,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/28579\/revisions\/28663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/media?parent=28579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/categories?post=28579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dadiscartagena.gov.co\/index.php\/wp-json\/wp\/v2\/tags?post=28579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}